{"id":1143,"date":"2024-12-20T16:01:03","date_gmt":"2024-12-20T16:01:03","guid":{"rendered":"https:\/\/timestreet.eu\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/"},"modified":"2025-01-26T18:42:23","modified_gmt":"2025-01-26T18:42:23","slug":"wiedereroeffnung-der-kathedrale-notre-dame-in-paris","status":"publish","type":"post","link":"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/","title":{"rendered":"Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris"},"content":{"rendered":"<p>Am Samstag, den 7. Dezember, fand in der Kathedrale Notre-Dame in Paris eine gro\u00dfe Zeremonie zur Wiederer\u00f6ffnung des Geb\u00e4udes statt. Das Feuer am 15. April 2019 hat das Geb\u00e4ude stark besch\u00e4digt und fast zum Einsturz gebracht. Nur durch das schnelle Eingreifen der Feuerwehr konnte die Katastrophe begrenzt werden. Auf die Zerst\u00f6rung folgte der lange Prozess des Wiederaufbaus und der Restaurierung von Notre-Dame. Heute k\u00f6nnen Sie die Kathedrale und ihr restauriertes Inneres (wieder) entdecken. Die lange Geschichte des Geb\u00e4udes hat es zu einem Ort der Macht und des Feierns gemacht, und in und um Notre-Dame fanden die gro\u00dfen Ereignisse der franz\u00f6sischen Geschichte statt, die Sie auf TimeStreet entdecken k\u00f6nnen. W\u00e4hrend der f\u00fcnfj\u00e4hrigen Bauarbeiten konnten die Forscher dank der Ausgrabungen des Institut national de recherches arch\u00e9ologiques pr\u00e9ventives, des nationalen franz\u00f6sischen Instituts f\u00fcr pr\u00e4ventive arch\u00e4ologische Forschung, zahlreiche Entdeckungen \u00fcber die Geschichte des Monuments, die verwendeten Bautechniken und die Geschichte des Ortes machen. Die \u00cele de la Cit\u00e9 ist seit der Antike bewohnt, und die Entdeckungen haben eine genauere Datierung erm\u00f6glicht, da Reste von Behausungen aus dem sp\u00e4ten Kaiserreich und Geb\u00e4ude aus der Karolingerzeit bis zum Mittelalter entdeckt wurden. Die Besiedlung der St\u00e4tte ist nun besser bekannt, ebenso wie die Entwicklung des Geb\u00e4udes selbst und seine Anpassung an die liturgischen Bed\u00fcrfnisse. Besonders beeindruckend ist die Entdeckung eines Lettners aus dem 13. Jahrhundert, einer verzierten Wand, die die Laien beim Gebet vom Klerus trennte. Der Lettner war aus Schriften und Inschriften bekannt, aber die Ausgrabung von Fragmenten hat es uns erm\u00f6glicht, ein besseres Verst\u00e4ndnis f\u00fcr sein Aussehen und seine Farben zu gewinnen. Der Lettner, der den Chor vom Rest des Geb\u00e4udes trennte, war mit Skulpturen bedeckt, die die Geschichte Christi darstellten und an die Zeremonie erinnerten, die dahinter stattfand. Das architektonische Ensemble blieb lange Zeit erhalten, wurde jedoch mehrfach umgestaltet, um es dem Zeitgeschmack anzupassen, bis es 1792, w\u00e4hrend der Revolutionszeit, zerst\u00f6rt wurde. Fragmente der Statuen wurden restauriert, um den Anstrich zu reparieren. All diese Entdeckungen haben unser Wissen \u00fcber die Kathedrale bereichert und das Bewusstsein daf\u00fcr gesch\u00e4rft, wie wichtig es ist, die Techniken des Denkmalschutzes zu \u00fcberdenken. Die Arbeiten wurden in zwei Phasen durchgef\u00fchrt, da Notre-Dame, die durch den Brand stark geschw\u00e4cht war, zun\u00e4chst gesichert und konsolidiert werden musste, bevor sich die Teams in das Geb\u00e4ude wagen konnten. Die Restaurierung von Notre-Dame war Gegenstand vieler Debatten, und Vorschl\u00e4ge, die Turmspitze von Viollet le Duc durch eine moderne Version zu ersetzen, wurden rundweg abgelehnt. Es wurde beschlossen, die Kathedrale 2019 in ihren urspr\u00fcnglichen Zustand vor dem Brand zur\u00fcckzuversetzen, was der Deontologie im Bereich des Kulturerbes und der Restaurierung entspricht, die in der Charta von Venedig von 1964 festgelegt wurde. Aber diese Entscheidung friert das Geb\u00e4ude auch in seinem Erscheinungsbild aus dem neunzehnten Jahrhundert und den vielen Ver\u00e4nderungen ein, die an Notre Dame de Paris vorgenommen wurden. Jahrhundert und die zahlreichen Ver\u00e4nderungen, die an Notre Dame de Paris vorgenommen wurden. Die Entscheidungen, die in dieser Zeit getroffen wurden, insbesondere von dem Architekten Eug\u00e8ne Viollet-le-duc, erinnern an die Entwicklung des Geschmacks und der Praktiken, an die Geschichte der Denkm\u00e4ler und an die Beziehung der Zeitgenossen zu ihrer Geschichte. Notre Dame ist eines der emblematischen Geb\u00e4ude von Paris, die Sie auf TimeStreet France entdecken k\u00f6nnen! Quelle:<\/p>\n<p><a href=\"https:\/\/notre-dame-de-paris.culture.gouv.fr\/fr\/la-preparation-de-la-restauration\">https:\/\/notre-dame-de-paris.culture.gouv.fr\/fr\/la-preparation-de-la-restauration<\/a><\/p>\n<p><a href=\"https:\/\/www.inrap.fr\/archeologie-de-notre-dame-de-paris-avancees-des-recherches-19536\">https:\/\/www.inrap.fr\/archeologie-de-notre-dame-de-paris-avancees-des-recherches-19536<\/a><\/p>\n<p><a href=\"https:\/\/www.beauxarts.com\/grand-format\/notre-dame-de-paris-des-decouvertes-spectaculaires-annoncees-par-les-archeologues\/\">https:\/\/www.beauxarts.com\/grand-format\/notre-dame-de-paris-des-decouvertes-spectaculaires-annoncees-par-les-archeologues\/<\/a><\/p>\n<p><a href=\"https:\/\/www.connaissancedesarts.com\/monuments-patrimoine\/notre-dame-paris\/dans-les-entrailles-de-notre-dame-de-paris-quest-ce-que-les-archeologues-ont-decouvert-sous-la-cathedrale-11194073\/\">https:\/\/www.connaissancedesarts.com\/monuments-patrimoine\/notre-dame-paris\/dans-les-entrailles-de-notre-dame-de-paris-quest-ce-que-les-archeologues-ont-decouvert-sous-la-cathedrale-11194073\/<\/a><\/p>\n<p>https:\/\/www.francetvinfo.fr\/culture\/patrimoine\/incendie-de-notre-dame-de-paris\/reouverture\/reouverture-de-notre-dame-de-paris-le-risque-de-pollution-au-plomb-est-il-completement-ecarte_6918677.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Samstag, den 7. Dezember, fand in der Kathedrale Notre-Dame in Paris eine gro\u00dfe Zeremonie zur Wiederer\u00f6ffnung des Geb\u00e4udes statt. Das Feuer am 15. April 2019 hat das Geb\u00e4ude stark besch\u00e4digt und fast zum Einsturz [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1541,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-1143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris | TimeStreet<\/title>\n<meta name=\"description\" content=\"Erleben Sie die gro\u00dfartige Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris nach der umfassenden Restaurierung nach dem verheerenden Brand.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris\" \/>\n<meta property=\"og:description\" content=\"Erleben Sie die gro\u00dfartige Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris nach der umfassenden Restaurierung nach dem verheerenden Brand.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/\" \/>\n<meta property=\"og:site_name\" content=\"TimeStreet\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-20T16:01:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-26T18:42:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/12\/iStock-660308204-copy_opt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"dejan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"dejan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\\\/\"},\"author\":{\"name\":\"dejan\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/#\\\/schema\\\/person\\\/2a00b4c43b60dd39d1949f2ce316ada0\"},\"headline\":\"Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris\",\"datePublished\":\"2024-12-20T16:01:03+00:00\",\"dateModified\":\"2025-01-26T18:42:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\\\/\"},\"wordCount\":611,\"publisher\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/timestreet.eu\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/iStock-660308204-copy_opt.jpg\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\\\/\",\"url\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\\\/\",\"name\":\"Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris | TimeStreet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/timestreet.eu\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/iStock-660308204-copy_opt.jpg\",\"datePublished\":\"2024-12-20T16:01:03+00:00\",\"dateModified\":\"2025-01-26T18:42:23+00:00\",\"description\":\"Erleben Sie die gro\u00dfartige Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris nach der umfassenden Restaurierung nach dem verheerenden Brand.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/timestreet.eu\\\/de\\\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\\\/#primaryimage\",\"url\":\"https:\\\/\\\/timestreet.eu\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/iStock-660308204-copy_opt.jpg\",\"contentUrl\":\"https:\\\/\\\/timestreet.eu\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/iStock-660308204-copy_opt.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"Notre Dame de Paris cathedral reflecting in river on sunrise, Paris, France\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/\",\"name\":\"TimeStreet App\",\"description\":\"Historical Travel Guide\",\"publisher\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/#organization\"},\"alternateName\":\"TimeStreet\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/#organization\",\"name\":\"TimeStreet\",\"url\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/timestreet.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/timestreet-logo-terracotta-512-x-512.png\",\"contentUrl\":\"https:\\\/\\\/timestreet.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/timestreet-logo-terracotta-512-x-512.png\",\"width\":2085,\"height\":2084,\"caption\":\"TimeStreet\"},\"image\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/timestreet.eu\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/#\\\/schema\\\/person\\\/2a00b4c43b60dd39d1949f2ce316ada0\",\"name\":\"dejan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afceeab548d0a8cc1e1349b6fde0039789dcc025da6802617278533425254801?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afceeab548d0a8cc1e1349b6fde0039789dcc025da6802617278533425254801?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afceeab548d0a8cc1e1349b6fde0039789dcc025da6802617278533425254801?s=96&d=mm&r=g\",\"caption\":\"dejan\"},\"sameAs\":[\"https:\\\/\\\/timestreet.eu\"],\"url\":\"https:\\\/\\\/timestreet.eu\\\/de\\\/author\\\/dejan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris | TimeStreet","description":"Erleben Sie die gro\u00dfartige Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris nach der umfassenden Restaurierung nach dem verheerenden Brand.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/","og_locale":"de_DE","og_type":"article","og_title":"Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris","og_description":"Erleben Sie die gro\u00dfartige Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris nach der umfassenden Restaurierung nach dem verheerenden Brand.","og_url":"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/","og_site_name":"TimeStreet","article_published_time":"2024-12-20T16:01:03+00:00","article_modified_time":"2025-01-26T18:42:23+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/12\/iStock-660308204-copy_opt.jpg","type":"image\/jpeg"}],"author":"dejan","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"dejan","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/#article","isPartOf":{"@id":"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/"},"author":{"name":"dejan","@id":"https:\/\/timestreet.eu\/de\/#\/schema\/person\/2a00b4c43b60dd39d1949f2ce316ada0"},"headline":"Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris","datePublished":"2024-12-20T16:01:03+00:00","dateModified":"2025-01-26T18:42:23+00:00","mainEntityOfPage":{"@id":"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/"},"wordCount":611,"publisher":{"@id":"https:\/\/timestreet.eu\/de\/#organization"},"image":{"@id":"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/12\/iStock-660308204-copy_opt.jpg","articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/","url":"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/","name":"Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris | TimeStreet","isPartOf":{"@id":"https:\/\/timestreet.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/#primaryimage"},"image":{"@id":"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/12\/iStock-660308204-copy_opt.jpg","datePublished":"2024-12-20T16:01:03+00:00","dateModified":"2025-01-26T18:42:23+00:00","description":"Erleben Sie die gro\u00dfartige Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris nach der umfassenden Restaurierung nach dem verheerenden Brand.","breadcrumb":{"@id":"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/#primaryimage","url":"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/12\/iStock-660308204-copy_opt.jpg","contentUrl":"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/12\/iStock-660308204-copy_opt.jpg","width":2000,"height":1333,"caption":"Notre Dame de Paris cathedral reflecting in river on sunrise, Paris, France"},{"@type":"BreadcrumbList","@id":"https:\/\/timestreet.eu\/de\/wiedereroeffnung-der-kathedrale-notre-dame-in-paris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/timestreet.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Wiederer\u00f6ffnung der Kathedrale Notre-Dame in Paris"}]},{"@type":"WebSite","@id":"https:\/\/timestreet.eu\/de\/#website","url":"https:\/\/timestreet.eu\/de\/","name":"TimeStreet App","description":"Historical Travel Guide","publisher":{"@id":"https:\/\/timestreet.eu\/de\/#organization"},"alternateName":"TimeStreet","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/timestreet.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/timestreet.eu\/de\/#organization","name":"TimeStreet","url":"https:\/\/timestreet.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/timestreet.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/08\/timestreet-logo-terracotta-512-x-512.png","contentUrl":"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/08\/timestreet-logo-terracotta-512-x-512.png","width":2085,"height":2084,"caption":"TimeStreet"},"image":{"@id":"https:\/\/timestreet.eu\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/timestreet.eu\/"]},{"@type":"Person","@id":"https:\/\/timestreet.eu\/de\/#\/schema\/person\/2a00b4c43b60dd39d1949f2ce316ada0","name":"dejan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/afceeab548d0a8cc1e1349b6fde0039789dcc025da6802617278533425254801?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/afceeab548d0a8cc1e1349b6fde0039789dcc025da6802617278533425254801?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/afceeab548d0a8cc1e1349b6fde0039789dcc025da6802617278533425254801?s=96&d=mm&r=g","caption":"dejan"},"sameAs":["https:\/\/timestreet.eu"],"url":"https:\/\/timestreet.eu\/de\/author\/dejan\/"}]}},"_links":{"self":[{"href":"https:\/\/timestreet.eu\/de\/wp-json\/wp\/v2\/posts\/1143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/timestreet.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/timestreet.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/timestreet.eu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/timestreet.eu\/de\/wp-json\/wp\/v2\/comments?post=1143"}],"version-history":[{"count":1,"href":"https:\/\/timestreet.eu\/de\/wp-json\/wp\/v2\/posts\/1143\/revisions"}],"predecessor-version":[{"id":1547,"href":"https:\/\/timestreet.eu\/de\/wp-json\/wp\/v2\/posts\/1143\/revisions\/1547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/timestreet.eu\/de\/wp-json\/wp\/v2\/media\/1541"}],"wp:attachment":[{"href":"https:\/\/timestreet.eu\/de\/wp-json\/wp\/v2\/media?parent=1143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/timestreet.eu\/de\/wp-json\/wp\/v2\/categories?post=1143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/timestreet.eu\/de\/wp-json\/wp\/v2\/tags?post=1143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}