{"id":548,"date":"2024-12-20T16:01:03","date_gmt":"2024-12-20T16:01:03","guid":{"rendered":"https:\/\/timestreet.eu\/548\/"},"modified":"2025-01-26T18:43:14","modified_gmt":"2025-01-26T18:43:14","slug":"548","status":"publish","type":"post","link":"https:\/\/timestreet.eu\/pt-pt\/548\/","title":{"rendered":"Reabertura da Catedral de Notre-Dame em Paris"},"content":{"rendered":"<p>No s\u00e1bado, 7 de dezembro, realizou-se uma grande cerim\u00f3nia na Catedral de Notre-Dame, em Paris, para assinalar a sua reabertura.<br \/>\nO inc\u00eandio de 15 de abril de 2019 causou grandes danos ao edif\u00edcio, que quase ruiu.<br \/>\nFoi apenas a r\u00e1pida interven\u00e7\u00e3o dos bombeiros que limitou a cat\u00e1strofe.<br \/>\nAp\u00f3s a destrui\u00e7\u00e3o, seguiu-se um longo processo de reconstru\u00e7\u00e3o e restauro de Notre-Dame.<br \/>\nPodes agora (re)descobrir a catedral e o seu interior restaurado.<br \/>\nA longa hist\u00f3ria do edif\u00edcio fez dele um lugar de poder e de celebra\u00e7\u00e3o, e foi em Notre-Dame e nos seus arredores que tiveram lugar os grandes acontecimentos da hist\u00f3ria francesa, que podes descobrir no TimeStreet.<br \/>\nOs cinco anos de trabalhos de constru\u00e7\u00e3o permitiram aos investigadores fazer numerosas descobertas sobre a hist\u00f3ria do monumento, as t\u00e9cnicas de constru\u00e7\u00e3o utilizadas e a hist\u00f3ria do local, gra\u00e7as \u00e0s escava\u00e7\u00f5es efectuadas pelo Institut national de recherches arch\u00e9ologiques pr\u00e9ventives, o instituto nacional franc\u00eas de investiga\u00e7\u00e3o arqueol\u00f3gica preventiva.<br \/>\nA \u00cele de la Cit\u00e9 foi habitada desde a Antiguidade, e as descobertas permitiram uma data\u00e7\u00e3o mais precisa, com a descoberta de vest\u00edgios de habita\u00e7\u00f5es do Imp\u00e9rio Tardio e de edif\u00edcios do per\u00edodo carol\u00edngio at\u00e9 \u00e0 Idade M\u00e9dia.<br \/>\nA ocupa\u00e7\u00e3o do local \u00e9 hoje mais conhecida, bem como a evolu\u00e7\u00e3o do pr\u00f3prio edif\u00edcio e a sua adapta\u00e7\u00e3o \u00e0s necessidades lit\u00fargicas.<br \/>\nO mais impressionante \u00e9 a descoberta de um biombo do s\u00e9culo XIII, uma parede ornamentada que separava os leigos do clero para a ora\u00e7\u00e3o.<br \/>\nO biombo era conhecido atrav\u00e9s de escritos e inscri\u00e7\u00f5es, mas a escava\u00e7\u00e3o de fragmentos permitiu-nos conhecer melhor o seu aspeto e as suas cores.<br \/>\nSeparando o coro do resto do edif\u00edcio, o biombo foi coberto com esculturas que retratam a hist\u00f3ria de Cristo e evocam a cerim\u00f3nia que teve lugar por detr\u00e1s dele.<br \/>\nO conjunto arquitet\u00f3nico foi preservado durante muito tempo, mas sofreu v\u00e1rias transforma\u00e7\u00f5es para se adaptar aos gostos contempor\u00e2neos, at\u00e9 ser destru\u00eddo em 1792, durante o per\u00edodo revolucion\u00e1rio.<br \/>\nForam restaurados fragmentos da estatu\u00e1ria para fixar a pintura.<br \/>\nTodas estas descobertas enriqueceram o nosso conhecimento da catedral e sensibilizaram-nos para a import\u00e2ncia de repensar as t\u00e9cnicas de prote\u00e7\u00e3o do patrim\u00f3nio.<br \/>\nOs trabalhos foram realizados em duas fases, uma vez que a Notre-Dame, profundamente enfraquecida pelo inc\u00eandio, teve primeiro de ser protegida e consolidada antes de as equipas poderem come\u00e7ar a entrar no edif\u00edcio.<br \/>\nO restauro de Notre-Dame foi objeto de um grande debate e as propostas de substitui\u00e7\u00e3o do pin\u00e1culo de Viollet le Duc por uma vers\u00e3o moderna foram rejeitadas por unanimidade.<br \/>\nFoi tomada a decis\u00e3o de repor a catedral no seu estado original, antes do inc\u00eandio de 2019, o que est\u00e1 em conformidade com a deontologia no dom\u00ednio do patrim\u00f3nio e do restauro estabelecida pela Carta de Veneza de 1964.<br \/>\nMas esta decis\u00e3o tamb\u00e9m congela o edif\u00edcio no seu aspeto do s\u00e9culo XIX e as muitas altera\u00e7\u00f5es introduzidas em Notre Dame de Paris.<br \/>\nAs escolhas feitas durante este per\u00edodo, nomeadamente pelo arquiteto Eug\u00e8ne Viollet-le-duc, recordam a evolu\u00e7\u00e3o dos gostos e das pr\u00e1ticas, a hist\u00f3ria dos monumentos e a rela\u00e7\u00e3o dos contempor\u00e2neos com a sua hist\u00f3ria.<br \/>\nNotre Dame \u00e9 um dos edif\u00edcios emblem\u00e1ticos de Paris que podes descobrir no TimeStreet France!<br \/>\nFonte:   <\/p>\n<p><a href=\"https:\/\/notre-dame-de-paris.culture.gouv.fr\/fr\/la-preparation-de-la-restauration\">https:\/\/notre-dame-de-paris.culture.gouv.fr\/fr\/la-preparation-de-la-restauration<\/a><\/p>\n<p><a href=\"https:\/\/www.inrap.fr\/archeologie-de-notre-dame-de-paris-avancees-des-recherches-19536\">https:\/\/www.inrap.fr\/archeologie-de-notre-dame-de-paris-avancees-des-recherches-19536<\/a><\/p>\n<p><a href=\"https:\/\/www.beauxarts.com\/grand-format\/notre-dame-de-paris-des-decouvertes-spectaculaires-annoncees-par-les-archeologues\/\">https:\/\/www.beauxarts.com\/grand-format\/notre-dame-de-paris-des-decouvertes-spectaculaires-annoncees-par-les-archeologues\/<\/a><\/p>\n<p><a href=\"https:\/\/www.connaissancedesarts.com\/monuments-patrimoine\/notre-dame-paris\/dans-les-entrailles-de-notre-dame-de-paris-quest-ce-que-les-archeologues-ont-decouvert-sous-la-cathedrale-11194073\/\">https:\/\/www.connaissancedesarts.com\/monuments-patrimoine\/notre-dame-paris\/dans-les-entrailles-de-notre-dame-de-paris-quest-ce-que-les-archeologues-ont-decouvert-sous-la-cathedrale-11194073\/<\/a><\/p>\n<p>https:\/\/www.francetvinfo.fr\/culture\/patrimoine\/incendie-de-notre-dame-de-paris\/reouverture\/reouverture-de-notre-dame-de-paris-le-risque-de-pollution-au-plomb-est-il-completement-ecarte_6918677.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No s\u00e1bado, 7 de dezembro, realizou-se uma grande cerim\u00f3nia na Catedral de Notre-Dame, em Paris, para assinalar a sua reabertura. O inc\u00eandio de 15 de abril de 2019 causou grandes danos ao edif\u00edcio, que quase [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":568,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Reabertura da Catedral de Notre-Dame em Paris | TimeStreet<\/title>\n<meta name=\"description\" content=\"Descobre a grande reabertura da Catedral de Notre-Dame em Paris, depois de um extenso restauro ap\u00f3s o inc\u00eandio devastador.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/timestreet.eu\/pt-pt\/548\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reabertura da Catedral de Notre-Dame em Paris\" \/>\n<meta property=\"og:description\" content=\"Descobre a grande reabertura da Catedral de Notre-Dame em Paris, depois de um extenso restauro ap\u00f3s o inc\u00eandio devastador.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/timestreet.eu\/pt-pt\/548\/\" \/>\n<meta property=\"og:site_name\" content=\"TimeStreet\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-20T16:01:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-26T18:43:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/12\/iStock-660308204-copy_opt.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"dejan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"dejan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/548\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/548\\\/\"},\"author\":{\"name\":\"dejan\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/#\\\/schema\\\/person\\\/2a00b4c43b60dd39d1949f2ce316ada0\"},\"headline\":\"Reabertura da Catedral de Notre-Dame em Paris\",\"datePublished\":\"2024-12-20T16:01:03+00:00\",\"dateModified\":\"2025-01-26T18:43:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/548\\\/\"},\"wordCount\":639,\"publisher\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/548\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/timestreet.eu\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/iStock-660308204-copy_opt.jpeg\",\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/548\\\/\",\"url\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/548\\\/\",\"name\":\"Reabertura da Catedral de Notre-Dame em Paris | TimeStreet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/548\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/548\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/timestreet.eu\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/iStock-660308204-copy_opt.jpeg\",\"datePublished\":\"2024-12-20T16:01:03+00:00\",\"dateModified\":\"2025-01-26T18:43:14+00:00\",\"description\":\"Descobre a grande reabertura da Catedral de Notre-Dame em Paris, depois de um extenso restauro ap\u00f3s o inc\u00eandio devastador.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/548\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/548\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/548\\\/#primaryimage\",\"url\":\"https:\\\/\\\/timestreet.eu\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/iStock-660308204-copy_opt.jpeg\",\"contentUrl\":\"https:\\\/\\\/timestreet.eu\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/iStock-660308204-copy_opt.jpeg\",\"width\":1200,\"height\":800,\"caption\":\"Notre Dame de Paris cathedral reflecting in river on sunrise, Paris, France\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/548\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reabertura da Catedral de Notre-Dame em Paris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/\",\"name\":\"TimeStreet App\",\"description\":\"Historical Travel Guide\",\"publisher\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/#organization\"},\"alternateName\":\"TimeStreet\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/#organization\",\"name\":\"TimeStreet\",\"url\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/timestreet.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/timestreet-logo-terracotta-512-x-512.png\",\"contentUrl\":\"https:\\\/\\\/timestreet.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/timestreet-logo-terracotta-512-x-512.png\",\"width\":2085,\"height\":2084,\"caption\":\"TimeStreet\"},\"image\":{\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/timestreet.eu\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/#\\\/schema\\\/person\\\/2a00b4c43b60dd39d1949f2ce316ada0\",\"name\":\"dejan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afceeab548d0a8cc1e1349b6fde0039789dcc025da6802617278533425254801?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afceeab548d0a8cc1e1349b6fde0039789dcc025da6802617278533425254801?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afceeab548d0a8cc1e1349b6fde0039789dcc025da6802617278533425254801?s=96&d=mm&r=g\",\"caption\":\"dejan\"},\"sameAs\":[\"https:\\\/\\\/timestreet.eu\"],\"url\":\"https:\\\/\\\/timestreet.eu\\\/pt-pt\\\/author\\\/dejan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Reabertura da Catedral de Notre-Dame em Paris | TimeStreet","description":"Descobre a grande reabertura da Catedral de Notre-Dame em Paris, depois de um extenso restauro ap\u00f3s o inc\u00eandio devastador.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/timestreet.eu\/pt-pt\/548\/","og_locale":"pt_PT","og_type":"article","og_title":"Reabertura da Catedral de Notre-Dame em Paris","og_description":"Descobre a grande reabertura da Catedral de Notre-Dame em Paris, depois de um extenso restauro ap\u00f3s o inc\u00eandio devastador.","og_url":"https:\/\/timestreet.eu\/pt-pt\/548\/","og_site_name":"TimeStreet","article_published_time":"2024-12-20T16:01:03+00:00","article_modified_time":"2025-01-26T18:43:14+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/12\/iStock-660308204-copy_opt.jpeg","type":"image\/jpeg"}],"author":"dejan","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"dejan","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/timestreet.eu\/pt-pt\/548\/#article","isPartOf":{"@id":"https:\/\/timestreet.eu\/pt-pt\/548\/"},"author":{"name":"dejan","@id":"https:\/\/timestreet.eu\/pt-pt\/#\/schema\/person\/2a00b4c43b60dd39d1949f2ce316ada0"},"headline":"Reabertura da Catedral de Notre-Dame em Paris","datePublished":"2024-12-20T16:01:03+00:00","dateModified":"2025-01-26T18:43:14+00:00","mainEntityOfPage":{"@id":"https:\/\/timestreet.eu\/pt-pt\/548\/"},"wordCount":639,"publisher":{"@id":"https:\/\/timestreet.eu\/pt-pt\/#organization"},"image":{"@id":"https:\/\/timestreet.eu\/pt-pt\/548\/#primaryimage"},"thumbnailUrl":"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/12\/iStock-660308204-copy_opt.jpeg","inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/timestreet.eu\/pt-pt\/548\/","url":"https:\/\/timestreet.eu\/pt-pt\/548\/","name":"Reabertura da Catedral de Notre-Dame em Paris | TimeStreet","isPartOf":{"@id":"https:\/\/timestreet.eu\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/timestreet.eu\/pt-pt\/548\/#primaryimage"},"image":{"@id":"https:\/\/timestreet.eu\/pt-pt\/548\/#primaryimage"},"thumbnailUrl":"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/12\/iStock-660308204-copy_opt.jpeg","datePublished":"2024-12-20T16:01:03+00:00","dateModified":"2025-01-26T18:43:14+00:00","description":"Descobre a grande reabertura da Catedral de Notre-Dame em Paris, depois de um extenso restauro ap\u00f3s o inc\u00eandio devastador.","breadcrumb":{"@id":"https:\/\/timestreet.eu\/pt-pt\/548\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/timestreet.eu\/pt-pt\/548\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/timestreet.eu\/pt-pt\/548\/#primaryimage","url":"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/12\/iStock-660308204-copy_opt.jpeg","contentUrl":"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/12\/iStock-660308204-copy_opt.jpeg","width":1200,"height":800,"caption":"Notre Dame de Paris cathedral reflecting in river on sunrise, Paris, France"},{"@type":"BreadcrumbList","@id":"https:\/\/timestreet.eu\/pt-pt\/548\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/timestreet.eu\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Reabertura da Catedral de Notre-Dame em Paris"}]},{"@type":"WebSite","@id":"https:\/\/timestreet.eu\/pt-pt\/#website","url":"https:\/\/timestreet.eu\/pt-pt\/","name":"TimeStreet App","description":"Historical Travel Guide","publisher":{"@id":"https:\/\/timestreet.eu\/pt-pt\/#organization"},"alternateName":"TimeStreet","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/timestreet.eu\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/timestreet.eu\/pt-pt\/#organization","name":"TimeStreet","url":"https:\/\/timestreet.eu\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/timestreet.eu\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/08\/timestreet-logo-terracotta-512-x-512.png","contentUrl":"https:\/\/timestreet.eu\/wp-content\/uploads\/2024\/08\/timestreet-logo-terracotta-512-x-512.png","width":2085,"height":2084,"caption":"TimeStreet"},"image":{"@id":"https:\/\/timestreet.eu\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/timestreet.eu\/"]},{"@type":"Person","@id":"https:\/\/timestreet.eu\/pt-pt\/#\/schema\/person\/2a00b4c43b60dd39d1949f2ce316ada0","name":"dejan","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/afceeab548d0a8cc1e1349b6fde0039789dcc025da6802617278533425254801?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/afceeab548d0a8cc1e1349b6fde0039789dcc025da6802617278533425254801?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/afceeab548d0a8cc1e1349b6fde0039789dcc025da6802617278533425254801?s=96&d=mm&r=g","caption":"dejan"},"sameAs":["https:\/\/timestreet.eu"],"url":"https:\/\/timestreet.eu\/pt-pt\/author\/dejan\/"}]}},"_links":{"self":[{"href":"https:\/\/timestreet.eu\/pt-pt\/wp-json\/wp\/v2\/posts\/548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/timestreet.eu\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/timestreet.eu\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/timestreet.eu\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/timestreet.eu\/pt-pt\/wp-json\/wp\/v2\/comments?post=548"}],"version-history":[{"count":3,"href":"https:\/\/timestreet.eu\/pt-pt\/wp-json\/wp\/v2\/posts\/548\/revisions"}],"predecessor-version":[{"id":1132,"href":"https:\/\/timestreet.eu\/pt-pt\/wp-json\/wp\/v2\/posts\/548\/revisions\/1132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/timestreet.eu\/pt-pt\/wp-json\/wp\/v2\/media\/568"}],"wp:attachment":[{"href":"https:\/\/timestreet.eu\/pt-pt\/wp-json\/wp\/v2\/media?parent=548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/timestreet.eu\/pt-pt\/wp-json\/wp\/v2\/categories?post=548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/timestreet.eu\/pt-pt\/wp-json\/wp\/v2\/tags?post=548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}